{"id":814,"date":"2019-07-04T16:56:42","date_gmt":"2019-07-04T14:56:42","guid":{"rendered":"https:\/\/www.smspescatoripra.it\/?p=814"},"modified":"2022-02-12T14:28:22","modified_gmt":"2022-02-12T13:28:22","slug":"centenario-di-fondazione-22-giugno-2019","status":"publish","type":"post","link":"https:\/\/www.smspescatoripra.it\/index.php\/2019\/07\/04\/centenario-di-fondazione-22-giugno-2019\/","title":{"rendered":"Centenario di fondazione &#8211; 22 giugno 2019"},"content":{"rendered":"\n<p>Sabato 22 giugno si sono conclusi i festeggiamenti per il centenario della nostra Societ\u00e0.<\/p>\n\n\n\n<p>Nel pomeriggio Mons. Canessa ha celebrato la messa in suffragio dei soci defunti della nostra Societ\u00e0 e della Banda Musicale di Pra\u2019 Carlo Colombi, che quest\u2019anno ha raggiunto i 150 anni di storia; alla funzione hanno preso parte i presidenti delle due realt\u00e0, il presidente del Municipio VII Ponente Claudio Chiarotti e molti soci.<\/p>\n\n\n\n<p>Dopo la celebrazione, ci siamo spostati alla Statua di San Pietro sul \u201cmucchio\u201d per la posa della targa commemorativa: qui, Guido Barbazza, socio della SMS ed esponente della FondAzione PRimA\u2019vera, ha letto l\u2019iscrizione, da lui composta, e Mons. Canessa ha conferito la sua benedizione. Sono intervenuti poi il presidente della FondAzione PRimA\u2019vera Niclo Calloni e il presidente Chiarotti; sullo sfondo, a fare da cornice a questo momento, vi era un gozzo storico ligure della famiglia Michelini. A seguire la Junior Band della Banda Musicale Carlo Colombi si \u00e8 esibita all\u2019interno del Palamare. Dopodich\u00e9 ci siamo spostati sulla passeggiata per l\u2019aperitivo, per il quale ringraziamo Bruzzone e Ferrari per il pesto, Panificio Rocco per focaccia e panini, Vini Allara per il celeberrimo Corochinato; durante l\u2019aperitivo sono stati distribuiti d\u00e9pliant con la storia della Societ\u00e0.<\/p>\n\n\n\n<p>Per concludere la serata in bellezza, la Big Band della banda Colombi, diretta dal maestro Enrico Oliveri, ha offerto alla cittadinanza lo spettacolo \u201cSwing sul Mare\u201d, presentato da Manuela Strigini.&nbsp;<\/p>\n\n\n\n<p>Conclusi i festeggiamenti, ci sentiamo in dovere di ringraziare ancora una volta e con estrema gratitudine tutti coloro che, in vario modo, hanno contribuito a rendere cos\u00ec speciali queste giornate di festa. Ci auguriamo che ci si possa ritrovare presto a vivere insieme altri momenti indimenticabili come questi e che la nostra Societ\u00e0 possa andare avanti nella sua storia continuando ad affermare quei valori che l\u2019hanno resa, in questi anni, un punto di riferimento importante non solo a Pra\u2019, ma in tutto il ponente genovese.<\/p>\n\n\n\n<ul class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery columns-3 is-cropped\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-1-1024x766.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"766\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-1-1024x766.jpg\" alt=\"\" data-id=\"872\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-1\/\" class=\"wp-image-872\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-1-1024x766.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-1-300x224.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-1-768x575.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-2-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-2-683x1024.jpg\" alt=\"\" data-id=\"873\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-2\/\" class=\"wp-image-873\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-2-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-2-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-2-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-3-1024x680.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"680\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-3-1024x680.jpg\" alt=\"\" data-id=\"874\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-3\/\" class=\"wp-image-874\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-3-1024x680.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-3-300x199.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-3-768x510.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-4-883x1024.jpg\"><img loading=\"lazy\" width=\"883\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-4-883x1024.jpg\" alt=\"\" data-id=\"875\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-4\/\" class=\"wp-image-875\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-4-883x1024.jpg 883w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-4-259x300.jpg 259w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-4-768x891.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-5-1024x745.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"745\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-5-1024x745.jpg\" alt=\"\" data-id=\"876\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-5\/\" class=\"wp-image-876\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-5-1024x745.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-5-300x218.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-5-768x559.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-6-1024x722.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"722\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-6-1024x722.jpg\" alt=\"\" data-id=\"877\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-6\/\" class=\"wp-image-877\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-6-1024x722.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-6-300x211.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-6-768x541.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-7-1024x746.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"746\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-7-1024x746.jpg\" alt=\"\" data-id=\"878\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-7\/\" class=\"wp-image-878\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-7-1024x746.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-7-300x219.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-7-768x560.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-8-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-8-683x1024.jpg\" alt=\"\" data-id=\"879\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-8\/\" class=\"wp-image-879\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-8-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-8-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-8-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-9-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-9-1024x683.jpg\" alt=\"\" data-id=\"880\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-9\/\" class=\"wp-image-880\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-9-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-9-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-9-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-10-1024x677.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"677\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-10-1024x677.jpg\" alt=\"\" data-id=\"881\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-10\/\" class=\"wp-image-881\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-10-1024x677.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-10-300x198.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-10-768x508.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-11-888x1024.jpg\"><img loading=\"lazy\" width=\"888\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-11-888x1024.jpg\" alt=\"\" data-id=\"882\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-11\/\" class=\"wp-image-882\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-11-888x1024.jpg 888w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-11-260x300.jpg 260w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-11-768x885.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-12-1024x693.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"693\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-12-1024x693.jpg\" alt=\"\" data-id=\"883\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-12\/\" class=\"wp-image-883\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-12-1024x693.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-12-300x203.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-12-768x520.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-13-698x1024.jpg\"><img loading=\"lazy\" width=\"698\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-13-698x1024.jpg\" alt=\"\" data-id=\"884\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-13\/\" class=\"wp-image-884\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-13-698x1024.jpg 698w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-13-205x300.jpg 205w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-13-768x1126.jpg 768w\" sizes=\"(max-width: 698px) 100vw, 698px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-14-1024x789.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"789\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-14-1024x789.jpg\" alt=\"\" data-id=\"885\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-14\/\" class=\"wp-image-885\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-14-1024x789.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-14-300x231.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-14-768x591.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-15-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-15-1024x683.jpg\" alt=\"\" data-id=\"886\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-15\/\" class=\"wp-image-886\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-15-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-15-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-15-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-16-1003x1024.jpg\"><img loading=\"lazy\" width=\"1003\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-16-1003x1024.jpg\" alt=\"\" data-id=\"887\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-16\/\" class=\"wp-image-887\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-16-1003x1024.jpg 1003w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-16-294x300.jpg 294w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-16-768x784.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-17-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-17-1024x683.jpg\" alt=\"\" data-id=\"888\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-17\/\" class=\"wp-image-888\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-17-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-17-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-17-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-18-1024x788.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"788\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-18-1024x788.jpg\" alt=\"\" data-id=\"889\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-18\/\" class=\"wp-image-889\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-18-1024x788.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-18-300x231.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-18-768x591.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-19-1024x711.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"711\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-19-1024x711.jpg\" alt=\"\" data-id=\"890\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-19\/\" class=\"wp-image-890\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-19-1024x711.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-19-300x208.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-19-768x533.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-20-840x1024.jpg\"><img loading=\"lazy\" width=\"840\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-20-840x1024.jpg\" alt=\"\" data-id=\"891\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-20\/\" class=\"wp-image-891\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-20-840x1024.jpg 840w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-20-246x300.jpg 246w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-20-768x937.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-21-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-21-1024x683.jpg\" alt=\"\" data-id=\"892\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-21\/\" class=\"wp-image-892\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-21-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-21-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-21-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-22-1024x474.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"474\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-22-1024x474.jpg\" alt=\"\" data-id=\"893\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-22\/\" class=\"wp-image-893\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-22-1024x474.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-22-300x139.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-22-768x356.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-23-980x1024.jpg\"><img loading=\"lazy\" width=\"980\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-23-980x1024.jpg\" alt=\"\" data-id=\"894\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-23\/\" class=\"wp-image-894\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-23-980x1024.jpg 980w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-23-287x300.jpg 287w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-23-768x802.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-24-763x1024.jpg\"><img loading=\"lazy\" width=\"763\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-24-763x1024.jpg\" alt=\"\" data-id=\"895\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-24\/\" class=\"wp-image-895\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-24-763x1024.jpg 763w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-24-224x300.jpg 224w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-24-768x1030.jpg 768w\" sizes=\"(max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-25-880x1024.jpg\"><img loading=\"lazy\" width=\"880\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-25-880x1024.jpg\" alt=\"\" data-id=\"896\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-25\/\" class=\"wp-image-896\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-25-880x1024.jpg 880w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-25-258x300.jpg 258w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-25-768x894.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-26-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-26-683x1024.jpg\" alt=\"\" data-id=\"897\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-26\/\" class=\"wp-image-897\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-26-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-26-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-26-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-27-665x1024.jpg\"><img loading=\"lazy\" width=\"665\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-27-665x1024.jpg\" alt=\"\" data-id=\"898\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-27\/\" class=\"wp-image-898\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-27-665x1024.jpg 665w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-27-195x300.jpg 195w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-27-768x1183.jpg 768w\" sizes=\"(max-width: 665px) 100vw, 665px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-28-1024x851.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"851\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-28-1024x851.jpg\" alt=\"\" data-id=\"899\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-28\/\" class=\"wp-image-899\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-28-1024x851.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-28-300x249.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-28-768x639.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-29-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-29-683x1024.jpg\" alt=\"\" data-id=\"900\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-29\/\" class=\"wp-image-900\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-29-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-29-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-29-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-30-815x1024.jpg\"><img loading=\"lazy\" width=\"815\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-30-815x1024.jpg\" alt=\"\" data-id=\"901\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-30\/\" class=\"wp-image-901\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-30-815x1024.jpg 815w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-30-239x300.jpg 239w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-30-768x965.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-31-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-31-683x1024.jpg\" alt=\"\" data-id=\"902\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-31\/\" class=\"wp-image-902\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-31-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-31-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-31-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-32-634x1024.jpg\"><img loading=\"lazy\" width=\"634\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-32-634x1024.jpg\" alt=\"\" data-id=\"903\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-32\/\" class=\"wp-image-903\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-32-634x1024.jpg 634w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-32-186x300.jpg 186w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-32-768x1240.jpg 768w\" sizes=\"(max-width: 634px) 100vw, 634px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-33-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-33-683x1024.jpg\" alt=\"\" data-id=\"904\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-33\/\" class=\"wp-image-904\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-33-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-33-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-33-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-34-721x1024.jpg\"><img loading=\"lazy\" width=\"721\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-34-721x1024.jpg\" alt=\"\" data-id=\"905\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-34\/\" class=\"wp-image-905\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-34-721x1024.jpg 721w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-34-211x300.jpg 211w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-34-768x1090.jpg 768w\" sizes=\"(max-width: 721px) 100vw, 721px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-35-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-35-683x1024.jpg\" alt=\"\" data-id=\"906\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-35\/\" class=\"wp-image-906\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-35-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-35-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-35-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-36-757x1024.jpg\"><img loading=\"lazy\" width=\"757\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-36-757x1024.jpg\" alt=\"\" data-id=\"907\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-36\/\" class=\"wp-image-907\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-36-757x1024.jpg 757w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-36-222x300.jpg 222w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-36-768x1039.jpg 768w\" sizes=\"(max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-37-1024x768.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-37-1024x768.jpg\" alt=\"\" data-id=\"908\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-37\/\" class=\"wp-image-908\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-37-1024x768.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-37-300x225.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-37-768x576.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-38-650x1024.jpg\"><img loading=\"lazy\" width=\"650\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-38-650x1024.jpg\" alt=\"\" data-id=\"909\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-38\/\" class=\"wp-image-909\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-38-650x1024.jpg 650w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-38-190x300.jpg 190w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-38-768x1210.jpg 768w\" sizes=\"(max-width: 650px) 100vw, 650px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-39-719x1024.jpg\"><img loading=\"lazy\" width=\"719\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-39-719x1024.jpg\" alt=\"\" data-id=\"910\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-39\/\" class=\"wp-image-910\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-39-719x1024.jpg 719w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-39-211x300.jpg 211w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-39-768x1094.jpg 768w\" sizes=\"(max-width: 719px) 100vw, 719px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-40-1024x705.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"705\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-40-1024x705.jpg\" alt=\"\" data-id=\"911\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-40\/\" class=\"wp-image-911\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-40-1024x705.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-40-300x207.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-40-768x529.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-41-1024x586.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"586\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-41-1024x586.jpg\" alt=\"\" data-id=\"912\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-41\/\" class=\"wp-image-912\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-41-1024x586.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-41-300x172.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-41-768x440.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-42-760x1024.jpg\"><img loading=\"lazy\" width=\"760\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-42-760x1024.jpg\" alt=\"\" data-id=\"913\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-42\/\" class=\"wp-image-913\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-42-760x1024.jpg 760w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-42-223x300.jpg 223w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-42-768x1034.jpg 768w\" sizes=\"(max-width: 706px) 89vw, (max-width: 767px) 82vw, 740px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-43-715x1024.jpg\"><img loading=\"lazy\" width=\"715\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-43-715x1024.jpg\" alt=\"\" data-id=\"914\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-43\/\" class=\"wp-image-914\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-43-715x1024.jpg 715w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-43-210x300.jpg 210w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-43-768x1100.jpg 768w\" sizes=\"(max-width: 715px) 100vw, 715px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-44-1024x1000.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"1000\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-44-1024x1000.jpg\" alt=\"\" data-id=\"915\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-44\/\" class=\"wp-image-915\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-44-1024x1000.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-44-300x293.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-44-768x750.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-45-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-45-683x1024.jpg\" alt=\"\" data-id=\"916\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-45\/\" class=\"wp-image-916\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-45-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-45-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-45-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-46-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-46-1024x683.jpg\" alt=\"\" data-id=\"917\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-46\/\" class=\"wp-image-917\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-46-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-46-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-46-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-47-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-47-1024x683.jpg\" alt=\"\" data-id=\"918\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-47\/\" class=\"wp-image-918\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-47-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-47-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-47-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-48-928x1024.jpg\"><img loading=\"lazy\" width=\"928\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-48-928x1024.jpg\" alt=\"\" data-id=\"919\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-48\/\" class=\"wp-image-919\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-48-928x1024.jpg 928w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-48-272x300.jpg 272w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-48-768x847.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-49-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-49-683x1024.jpg\" alt=\"\" data-id=\"920\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-49\/\" class=\"wp-image-920\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-49-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-49-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-49-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-50-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-50-683x1024.jpg\" alt=\"\" data-id=\"921\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-50\/\" class=\"wp-image-921\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-50-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-50-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-50-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-51-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-51-1024x683.jpg\" alt=\"\" data-id=\"922\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-51\/\" class=\"wp-image-922\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-51-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-51-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-51-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-52-1024x655.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"655\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-52-1024x655.jpg\" alt=\"\" data-id=\"923\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-52\/\" class=\"wp-image-923\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-52-1024x655.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-52-300x192.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-52-768x491.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-53-1024x490.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"490\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-53-1024x490.jpg\" alt=\"\" data-id=\"924\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-53\/\" class=\"wp-image-924\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-53-1024x490.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-53-300x144.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-53-768x368.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-54-690x1024.jpg\"><img loading=\"lazy\" width=\"690\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-54-690x1024.jpg\" alt=\"\" data-id=\"925\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-54\/\" class=\"wp-image-925\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-54-690x1024.jpg 690w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-54-202x300.jpg 202w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-54-768x1140.jpg 768w\" sizes=\"(max-width: 690px) 100vw, 690px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-55-1024x732.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"732\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-55-1024x732.jpg\" alt=\"\" data-id=\"926\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-55\/\" class=\"wp-image-926\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-55-1024x732.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-55-300x214.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-55-768x549.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-56-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-56-1024x683.jpg\" alt=\"\" data-id=\"927\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-56\/\" class=\"wp-image-927\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-56-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-56-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-56-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-57-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-57-1024x683.jpg\" alt=\"\" data-id=\"928\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-57\/\" class=\"wp-image-928\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-57-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-57-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-57-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-58-1024x761.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"761\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-58-1024x761.jpg\" alt=\"\" data-id=\"929\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-58\/\" class=\"wp-image-929\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-58-1024x761.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-58-300x223.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-58-768x571.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-59-1024x629.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"629\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-59-1024x629.jpg\" alt=\"\" data-id=\"930\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-59\/\" class=\"wp-image-930\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-59-1024x629.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-59-300x184.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-59-768x471.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-60-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-60-1024x683.jpg\" alt=\"\" data-id=\"931\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-60\/\" class=\"wp-image-931\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-60-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-60-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-60-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-61-1024x642.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"642\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-61-1024x642.jpg\" alt=\"\" data-id=\"932\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-61\/\" class=\"wp-image-932\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-61-1024x642.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-61-300x188.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-61-768x482.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-62-1024x643.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"643\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-62-1024x643.jpg\" alt=\"\" data-id=\"933\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-62\/\" class=\"wp-image-933\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-62-1024x643.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-62-300x188.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-62-768x482.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-63-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-63-1024x683.jpg\" alt=\"\" data-id=\"934\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-63\/\" class=\"wp-image-934\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-63-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-63-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-63-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-64-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-64-1024x683.jpg\" alt=\"\" data-id=\"935\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-64\/\" class=\"wp-image-935\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-64-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-64-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-64-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-65-1024x761.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"761\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-65-1024x761.jpg\" alt=\"\" data-id=\"936\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-65\/\" class=\"wp-image-936\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-65-1024x761.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-65-300x223.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-65-768x571.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-66-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-66-1024x683.jpg\" alt=\"\" data-id=\"937\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-66\/\" class=\"wp-image-937\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-66-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-66-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-66-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-67-1024x550.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"550\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-67-1024x550.jpg\" alt=\"\" data-id=\"938\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-67\/\" class=\"wp-image-938\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-67-1024x550.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-67-300x161.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-67-768x413.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-68-1024x582.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"582\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-68-1024x582.jpg\" alt=\"\" data-id=\"939\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-68\/\" class=\"wp-image-939\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-68-1024x582.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-68-300x170.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-68-768x436.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-69-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-69-683x1024.jpg\" alt=\"\" data-id=\"940\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-69\/\" class=\"wp-image-940\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-69-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-69-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-69-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-70-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-70-683x1024.jpg\" alt=\"\" data-id=\"941\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-70\/\" class=\"wp-image-941\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-70-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-70-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-70-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-71-683x1024.jpg\"><img loading=\"lazy\" width=\"683\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-71-683x1024.jpg\" alt=\"\" data-id=\"942\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-71\/\" class=\"wp-image-942\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-71-683x1024.jpg 683w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-71-200x300.jpg 200w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-71-768x1152.jpg 768w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-72-1024x664.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"664\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-72-1024x664.jpg\" alt=\"\" data-id=\"943\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-72\/\" class=\"wp-image-943\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-72-1024x664.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-72-300x195.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-72-768x498.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-73-843x1024.jpg\"><img loading=\"lazy\" width=\"843\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-73-843x1024.jpg\" alt=\"\" data-id=\"944\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-73\/\" class=\"wp-image-944\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-73-843x1024.jpg 843w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-73-247x300.jpg 247w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-73-768x933.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-74-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-74-1024x683.jpg\" alt=\"\" data-id=\"945\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-74\/\" class=\"wp-image-945\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-74-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-74-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-74-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-75-1024x636.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"636\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-75-1024x636.jpg\" alt=\"\" data-id=\"946\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-75\/\" class=\"wp-image-946\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-75-1024x636.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-75-300x186.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-75-768x477.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-76-1024x683.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"683\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-76-1024x683.jpg\" alt=\"\" data-id=\"947\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-76\/\" class=\"wp-image-947\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-76-1024x683.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-76-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-76-768x512.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-77-1024x686.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"686\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-77-1024x686.jpg\" alt=\"\" data-id=\"948\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-77\/\" class=\"wp-image-948\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-77-1024x686.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-77-300x201.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-77-768x515.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-78-1024x605.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"605\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-78-1024x605.jpg\" alt=\"\" data-id=\"949\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-78\/\" class=\"wp-image-949\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-78-1024x605.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-78-300x177.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-78-768x454.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-79-1024x676.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"676\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-79-1024x676.jpg\" alt=\"\" data-id=\"950\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-79\/\" class=\"wp-image-950\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-79-1024x676.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-79-300x198.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-79-768x507.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-80-1024x451.jpg\"><img loading=\"lazy\" width=\"1024\" height=\"451\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-80-1024x451.jpg\" alt=\"\" data-id=\"951\" data-link=\"https:\/\/www.smspescatoripra.it\/22-giugno-2019-80\/\" class=\"wp-image-951\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-80-1024x451.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-80-300x132.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/07\/22-giugno-2019-80-768x338.jpg 768w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/a><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Sabato 22 giugno si sono conclusi i festeggiamenti per il centenario della nostra Societ\u00e0. Nel pomeriggio Mons. Canessa ha celebrato la messa in suffragio dei soci defunti della nostra Societ\u00e0 e della Banda Musicale di Pra\u2019 Carlo Colombi, che quest\u2019anno ha raggiunto i 150 anni di storia; alla funzione hanno preso parte i presidenti delle &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/07\/04\/centenario-di-fondazione-22-giugno-2019\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Centenario di fondazione &#8211; 22 giugno 2019&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[17],"tags":[],"_links":{"self":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/814"}],"collection":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/comments?post=814"}],"version-history":[{"count":2,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/814\/revisions"}],"predecessor-version":[{"id":952,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/814\/revisions\/952"}],"wp:attachment":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/media?parent=814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/categories?post=814"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/tags?post=814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}