{"id":631,"date":"2019-05-15T08:42:30","date_gmt":"2019-05-15T06:42:30","guid":{"rendered":"https:\/\/www.smspescatoripra.it\/?p=631"},"modified":"2019-06-13T12:05:16","modified_gmt":"2019-06-13T10:05:16","slug":"vivere-il-mare","status":"publish","type":"post","link":"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/","title":{"rendered":"Vivere il Mare"},"content":{"rendered":"\n<p><strong>Attivit\u00e0 2019 Gruppo\nSportivo SMS Pescatori Pra&#8217;<\/strong><\/p>\n\n\n\n<p>Il gruppo nasce dalla passione di alcuni soci\/amici, con la\nfinalit\u00e0 di organizzare e promuovere attivit\u00e0 socio culturali e sportive sulla\nFascia di Rispetto di Pra&#8217;. Per realizzare questo nostro sogno abbiamo attivato\nuna rete di collaborazione con altri soggetti, l&#8217;Istituto Comprensivo di Pra&#8217;,\nl&#8217;Istituto Comprensivo di Pegli, Cooperativa Sociale Omnibus e Coop Incontri di\nCoop Liguria. Dal 15 Aprile, giorno in cui abbiamo aperto la nostra sede sulla\nfascia di rispetto, abbiamo organizzato un fitto programma che propone 10\nincontri nei mesi di Aprile, Maggio e Giugno 2019, che vedr\u00e0 la partecipazione\ndi circa 300 persone di ogni et\u00e0.<\/p>\n\n\n\n<p>Il progetto \u00abVivere il mare\u00bb, mira principalmente a raggiungere questo scopo: valorizzare la nostra comunit\u00e0, tramite un percorso rivolto alle scuole e alle persone della terza et\u00e0,&nbsp; con visite guidate da Ninetto Durante e Gianni Orezzi al nostro centro storico <strong>\u201cI Risseu\u201d<\/strong>, al piccolo museo di arte marinaresca dei fratelli Michelini, alla chiesa di San Pietro, la meridiana collocata nella nostra sede della fascia di rispetto,e con l&#8217;occasione ringraziamo la societ\u00e0 Porto Nuovo nella persona di Gianpaolo Nasone per la sua disponibilit\u00e0, alla cooperativa pescatori \u201cSan Pietro\u201de ai Barcaioli delle Grazie che ci hanno permesso di vedere Pra&#8217; dal mare.<\/p>\n\n\n\n<p>Vogliamo che la nostra societ\u00e0 continui ad essere un luogo di\ncondivisione, che unisca progetti differenti ma convergenti, un piccolo polo\nrivolto alla collettivit\u00e0.<\/p>\n\n\n\n<ul class=\"wp-container-2 wp-block-gallery-1 wp-block-gallery columns-3 is-cropped\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0024-768x1024.jpg\" alt=\"\" data-id=\"657\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0024\/\" class=\"wp-image-657\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0024-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0024-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0024.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0023-768x1024.jpg\" alt=\"\" data-id=\"656\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0023\/\" class=\"wp-image-656\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0023-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0023-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0023.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0022-768x1024.jpg\" alt=\"\" data-id=\"655\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0022\/\" class=\"wp-image-655\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0022-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0022-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0022.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0021-768x1024.jpg\" alt=\"\" data-id=\"654\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0021\/\" class=\"wp-image-654\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0021-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0021-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0021.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-1024x768.jpg\" alt=\"\" data-id=\"653\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0020\/\" class=\"wp-image-653\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-1024x768.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-300x225.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-768x576.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020.jpg 1600w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0018-768x1024.jpg\" alt=\"\" data-id=\"652\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0018\/\" class=\"wp-image-652\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0018-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0018-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0018.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0017-768x1024.jpg\" alt=\"\" data-id=\"651\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0017\/\" class=\"wp-image-651\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0017-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0017-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0017.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0016-768x1024.jpg\" alt=\"\" data-id=\"650\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0016\/\" class=\"wp-image-650\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0016-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0016-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0016.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0015-768x1024.jpg\" alt=\"\" data-id=\"649\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0015\/\" class=\"wp-image-649\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0015-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0015-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0015.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0014-768x1024.jpg\" alt=\"\" data-id=\"648\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0014\/\" class=\"wp-image-648\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0014-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0014-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0014.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0012-768x1024.jpg\" alt=\"\" data-id=\"647\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0012\/\" class=\"wp-image-647\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0012-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0012-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0012.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0011-768x1024.jpg\" alt=\"\" data-id=\"646\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0011\/\" class=\"wp-image-646\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0011-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0011-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0011.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0010-768x1024.jpg\" alt=\"\" data-id=\"645\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0010\/\" class=\"wp-image-645\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0010-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0010-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0010.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-1024x768.jpg\" alt=\"\" data-id=\"644\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0009\/\" class=\"wp-image-644\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-1024x768.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-300x225.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-768x576.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009.jpg 1600w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0008-768x1024.jpg\" alt=\"\" data-id=\"643\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0008\/\" class=\"wp-image-643\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0008-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0008-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0008.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0006-768x1024.jpg\" alt=\"\" data-id=\"642\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0006\/\" class=\"wp-image-642\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0006-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0006-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0006.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-576x1024.jpg\" alt=\"\" data-id=\"641\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0004\/\" class=\"wp-image-641\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-576x1024.jpg 576w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-169x300.jpg 169w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-768x1365.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004.jpg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-576x1024.jpg\" alt=\"\" data-id=\"640\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0002\/\" class=\"wp-image-640\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-576x1024.jpg 576w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-169x300.jpg 169w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-768x1365.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002.jpg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-576x1024.jpg\" alt=\"\" data-id=\"638\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0000\/\" class=\"wp-image-638\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-576x1024.jpg 576w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-169x300.jpg 169w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-768x1365.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000.jpg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-576x1024.jpg\" alt=\"\" data-id=\"639\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0001\/\" class=\"wp-image-639\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-576x1024.jpg 576w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-169x300.jpg 169w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-768x1365.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001.jpg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-2-576x1024.jpg\" alt=\"\" data-id=\"681\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0000-3\/\" class=\"wp-image-681\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-2-576x1024.jpg 576w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-2-169x300.jpg 169w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-2-768x1365.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0000-2.jpg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-2-576x1024.jpg\" alt=\"\" data-id=\"682\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0001-3\/\" class=\"wp-image-682\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-2-576x1024.jpg 576w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-2-169x300.jpg 169w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-2-768x1365.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0001-2.jpg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-2-576x1024.jpg\" alt=\"\" data-id=\"683\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0002-3\/\" class=\"wp-image-683\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-2-576x1024.jpg 576w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-2-169x300.jpg 169w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-2-768x1365.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0002-2.jpg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"576\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-2-576x1024.jpg\" alt=\"\" data-id=\"684\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0004-3\/\" class=\"wp-image-684\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-2-576x1024.jpg 576w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-2-169x300.jpg 169w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-2-768x1365.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0004-2.jpg 900w\" sizes=\"(max-width: 576px) 100vw, 576px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0006-2-768x1024.jpg\" alt=\"\" data-id=\"685\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0006-3\/\" class=\"wp-image-685\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0006-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0006-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0006-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0008-2-768x1024.jpg\" alt=\"\" data-id=\"686\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0008-3\/\" class=\"wp-image-686\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0008-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0008-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0008-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-2-1024x768.jpg\" alt=\"\" data-id=\"687\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0009-3\/\" class=\"wp-image-687\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-2-1024x768.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-2-300x225.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-2-768x576.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0009-2.jpg 1600w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0010-2-768x1024.jpg\" alt=\"\" data-id=\"688\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0010-3\/\" class=\"wp-image-688\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0010-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0010-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0010-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0011-2-768x1024.jpg\" alt=\"\" data-id=\"689\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0011-3\/\" class=\"wp-image-689\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0011-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0011-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0011-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0012-2-768x1024.jpg\" alt=\"\" data-id=\"690\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0012-3\/\" class=\"wp-image-690\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0012-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0012-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0012-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0014-2-768x1024.jpg\" alt=\"\" data-id=\"691\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0014-3\/\" class=\"wp-image-691\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0014-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0014-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0014-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0015-2-768x1024.jpg\" alt=\"\" data-id=\"692\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0015-3\/\" class=\"wp-image-692\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0015-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0015-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0015-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0016-2-768x1024.jpg\" alt=\"\" data-id=\"693\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0016-3\/\" class=\"wp-image-693\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0016-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0016-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0016-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0017-2-768x1024.jpg\" alt=\"\" data-id=\"694\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0017-3\/\" class=\"wp-image-694\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0017-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0017-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0017-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0018-2-768x1024.jpg\" alt=\"\" data-id=\"695\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0018-3\/\" class=\"wp-image-695\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0018-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0018-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0018-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"1024\" height=\"768\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-2-1024x768.jpg\" alt=\"\" data-id=\"696\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0020-3\/\" class=\"wp-image-696\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-2-1024x768.jpg 1024w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-2-300x225.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-2-768x576.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0020-2.jpg 1600w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0021-2-768x1024.jpg\" alt=\"\" data-id=\"697\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0021-3\/\" class=\"wp-image-697\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0021-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0021-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0021-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0022-2-768x1024.jpg\" alt=\"\" data-id=\"698\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0022-3\/\" class=\"wp-image-698\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0022-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0022-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0022-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0023-2-768x1024.jpg\" alt=\"\" data-id=\"699\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0023-3\/\" class=\"wp-image-699\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0023-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0023-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0023-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0024-2-768x1024.jpg\" alt=\"\" data-id=\"700\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0024-3\/\" class=\"wp-image-700\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0024-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0024-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0024-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" width=\"768\" height=\"1024\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0025-2-768x1024.jpg\" alt=\"\" data-id=\"701\" data-link=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/img-20190501-wa0025-3\/\" class=\"wp-image-701\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0025-2-768x1024.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0025-2-225x300.jpg 225w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2019\/05\/IMG-20190501-WA0025-2.jpg 1200w\" sizes=\"(max-width: 767px) 89vw, (max-width: 1000px) 54vw, (max-width: 1071px) 543px, 580px\" \/><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Attivit\u00e0 2019 Gruppo Sportivo SMS Pescatori Pra&#8217; Il gruppo nasce dalla passione di alcuni soci\/amici, con la finalit\u00e0 di organizzare e promuovere attivit\u00e0 socio culturali e sportive sulla Fascia di Rispetto di Pra&#8217;. Per realizzare questo nostro sogno abbiamo attivato una rete di collaborazione con altri soggetti, l&#8217;Istituto Comprensivo di Pra&#8217;, l&#8217;Istituto Comprensivo di Pegli, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.smspescatoripra.it\/index.php\/2019\/05\/15\/vivere-il-mare\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Vivere il Mare&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[4],"tags":[],"_links":{"self":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/631"}],"collection":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/comments?post=631"}],"version-history":[{"count":2,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/631\/revisions"}],"predecessor-version":[{"id":702,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/631\/revisions\/702"}],"wp:attachment":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/media?parent=631"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/categories?post=631"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/tags?post=631"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}