{"id":608,"date":"2018-10-21T17:43:01","date_gmt":"2018-10-21T15:43:01","guid":{"rendered":"http:\/\/www.smspescatoripra.it\/?p=608"},"modified":"2018-10-21T17:43:01","modified_gmt":"2018-10-21T15:43:01","slug":"traina-sociale-gara-a-coppie","status":"publish","type":"post","link":"https:\/\/www.smspescatoripra.it\/index.php\/2018\/10\/21\/traina-sociale-gara-a-coppie\/","title":{"rendered":"Traina Sociale Gara a coppie"},"content":{"rendered":"<p>Si \u00e8 svolta nella mattina di domenica 21 ottobre un\u00a0 tradizionale appuntamento sociale che vede protagonisti i nostri associati battersi per un podio per la disciplina pi\u00f9 amata , la gara alla traina , 15 le imbarcazioni partecipanti per 30 pescatori armati di canne e esche artificiali , al via intorno alle 7.30 del mattino e fino alle ore 11.00. Giornata splendida senza vento e moto ondoso , povera di mangianze ,\u00a0 e quindi in tanti a prendere &#8220;capotto&#8221; tranne la coppia Franco Stampa e Liotta Paolo che con due belle Lecce per un totale di 4,775 Kg si sono aggiudicati il 1\u00b0 premio , a seguire Sacco e Riganti con un paio di\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 &#8221; Cavalle &#8220;, e al terzo posto Devita e Costa . A classifica stilata ,rinfresco\u00a0 e premi per tutti. Un saluto a tutti e un invito alla prossima gara .<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolta nella mattina di domenica 21 ottobre un\u00a0 tradizionale appuntamento sociale che vede protagonisti i nostri associati battersi per un podio per la disciplina pi\u00f9 amata , la gara alla traina , 15 le imbarcazioni partecipanti per 30 pescatori armati di canne e esche artificiali , al via intorno alle 7.30 del mattino &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/www.smspescatoripra.it\/index.php\/2018\/10\/21\/traina-sociale-gara-a-coppie\/\" class=\"more-link\">Leggi tutto<span class=\"screen-reader-text\"> &#8220;Traina Sociale Gara a coppie&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[9],"tags":[],"_links":{"self":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/608"}],"collection":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/comments?post=608"}],"version-history":[{"count":1,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/608\/revisions"}],"predecessor-version":[{"id":609,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/posts\/608\/revisions\/609"}],"wp:attachment":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/media?parent=608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/categories?post=608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/tags?post=608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}