{"id":215,"date":"2017-09-07T18:39:02","date_gmt":"2017-09-07T16:39:02","guid":{"rendered":"http:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13.jpg"},"modified":"2017-09-07T18:39:02","modified_gmt":"2017-09-07T16:39:02","slug":"sanpietro2017-13","status":"inherit","type":"attachment","link":"https:\/\/www.smspescatoripra.it\/index.php\/2017\/06\/28\/processione-in-mare\/sanpietro2017-13\/","title":{"rendered":"SanPietro2017 &#8211; 13"},"author":1,"comment_status":"open","ping_status":"closed","template":"","meta":[],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13.jpg'><img width=\"300\" height=\"200\" src=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-300x200.jpg\" class=\"attachment-medium size-medium\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-300x200.jpg 300w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-768x512.jpg 768w, https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-1024x683.jpg 1024w\" sizes=\"100vw\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":3888,"height":2592,"file":"2017\/06\/SanPietro2017-13.jpg","sizes":{"thumbnail":{"file":"SanPietro2017-13-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-150x150.jpg"},"medium":{"file":"SanPietro2017-13-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-300x200.jpg"},"medium_large":{"file":"SanPietro2017-13-768x512.jpg","width":768,"height":512,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-768x512.jpg"},"large":{"file":"SanPietro2017-13-1024x683.jpg","width":1024,"height":683,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-1024x683.jpg"},"twentyseventeen-featured-image":{"file":"SanPietro2017-13-2000x1200.jpg","width":2000,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-2000x1200.jpg"},"twentyseventeen-thumbnail-avatar":{"file":"SanPietro2017-13-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13-100x100.jpg"},"full":{"file":"SanPietro2017-13.jpg","width":3888,"height":2592,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"1498685377","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":196,"source_url":"https:\/\/www.smspescatoripra.it\/wp-content\/uploads\/2017\/06\/SanPietro2017-13.jpg","_links":{"self":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/media\/215"}],"collection":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smspescatoripra.it\/index.php\/wp-json\/wp\/v2\/comments?post=215"}]}}